{"id":17210,"date":"2022-01-07T15:45:53","date_gmt":"2022-01-07T14:45:53","guid":{"rendered":"https:\/\/schlosshotel-fleesensee.com\/rooms-suites\/rooms\/park-zimmer\/"},"modified":"2025-09-16T09:53:26","modified_gmt":"2025-09-16T07:53:26","slug":"park-rooms","status":"publish","type":"page","link":"https:\/\/schlosshotel-fleesensee.com\/en\/rooms-suites\/rooms\/park-rooms\/","title":{"rendered":"Park Rooms"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":17199,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"layout-builder.php","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-17210","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Park Rooms | SCHLOSS Fleesensee<\/title>\n<meta name=\"description\" content=\"Park Room - Timeless and flooded with light \u2713 Optionally bookable with terrace \u2713 Direct access to the castle park \u27a4 Book your stay now!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schlosshotel-fleesensee.com\/en\/rooms-suites\/rooms\/park-rooms\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Park Rooms | SCHLOSS Fleesensee\" \/>\n<meta property=\"og:description\" content=\"Park Room - Timeless and flooded with light \u2713 Optionally bookable with terrace \u2713 Direct access to the castle park \u27a4 Book your stay now!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schlosshotel-fleesensee.com\/en\/rooms-suites\/rooms\/park-rooms\/\" \/>\n<meta property=\"og:site_name\" content=\"Schlosshotel Fleesensee\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-16T07:53:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schlosshotel-fleesensee.com\\\/en\\\/rooms-suites\\\/rooms\\\/park-rooms\\\/\",\"url\":\"https:\\\/\\\/schlosshotel-fleesensee.com\\\/en\\\/rooms-suites\\\/rooms\\\/park-rooms\\\/\",\"name\":\"Park Rooms | SCHLOSS Fleesensee\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schlosshotel-fleesensee.com\\\/en\\\/#website\"},\"datePublished\":\"2022-01-07T14:45:53+00:00\",\"dateModified\":\"2025-09-16T07:53:26+00:00\",\"description\":\"Park Room - Timeless and flooded with light \u2713 Optionally bookable with terrace \u2713 Direct access to the castle park \u27a4 Book your stay now!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schlosshotel-fleesensee.com\\\/en\\\/rooms-suites\\\/rooms\\\/park-rooms\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schlosshotel-fleesensee.com\\\/en\\\/rooms-suites\\\/rooms\\\/park-rooms\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schlosshotel-fleesensee.com\\\/en\\\/rooms-suites\\\/rooms\\\/park-rooms\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schlosshotel-fleesensee.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rooms &#038; Suites\",\"item\":\"https:\\\/\\\/schlosshotel-fleesensee.com\\\/en\\\/rooms-suites\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rooms\",\"item\":\"https:\\\/\\\/schlosshotel-fleesensee.com\\\/en\\\/rooms-suites\\\/rooms\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Park Rooms\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schlosshotel-fleesensee.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/schlosshotel-fleesensee.com\\\/en\\\/\",\"name\":\"Schlosshotel Fleesensee\",\"description\":\"Endlich Urlaub. Endlich Ich.\",\"publisher\":{\"@id\":\"https:\\\/\\\/schlosshotel-fleesensee.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schlosshotel-fleesensee.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schlosshotel-fleesensee.com\\\/en\\\/#organization\",\"name\":\"Fleesensee Schlosshotel GmbH\",\"url\":\"https:\\\/\\\/schlosshotel-fleesensee.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/schlosshotel-fleesensee.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schlosshotel-fleesensee.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/schloss_fleesensee_logo.svg\",\"contentUrl\":\"https:\\\/\\\/schlosshotel-fleesensee.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/schloss_fleesensee_logo.svg\",\"width\":77,\"height\":120,\"caption\":\"Fleesensee Schlosshotel GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/schlosshotel-fleesensee.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Park Rooms | SCHLOSS Fleesensee","description":"Park Room - Timeless and flooded with light \u2713 Optionally bookable with terrace \u2713 Direct access to the castle park \u27a4 Book your stay now!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schlosshotel-fleesensee.com\/en\/rooms-suites\/rooms\/park-rooms\/","og_locale":"en_US","og_type":"article","og_title":"Park Rooms | SCHLOSS Fleesensee","og_description":"Park Room - Timeless and flooded with light \u2713 Optionally bookable with terrace \u2713 Direct access to the castle park \u27a4 Book your stay now!","og_url":"https:\/\/schlosshotel-fleesensee.com\/en\/rooms-suites\/rooms\/park-rooms\/","og_site_name":"Schlosshotel Fleesensee","article_modified_time":"2025-09-16T07:53:26+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schlosshotel-fleesensee.com\/en\/rooms-suites\/rooms\/park-rooms\/","url":"https:\/\/schlosshotel-fleesensee.com\/en\/rooms-suites\/rooms\/park-rooms\/","name":"Park Rooms | SCHLOSS Fleesensee","isPartOf":{"@id":"https:\/\/schlosshotel-fleesensee.com\/en\/#website"},"datePublished":"2022-01-07T14:45:53+00:00","dateModified":"2025-09-16T07:53:26+00:00","description":"Park Room - Timeless and flooded with light \u2713 Optionally bookable with terrace \u2713 Direct access to the castle park \u27a4 Book your stay now!","breadcrumb":{"@id":"https:\/\/schlosshotel-fleesensee.com\/en\/rooms-suites\/rooms\/park-rooms\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schlosshotel-fleesensee.com\/en\/rooms-suites\/rooms\/park-rooms\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schlosshotel-fleesensee.com\/en\/rooms-suites\/rooms\/park-rooms\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schlosshotel-fleesensee.com\/en\/"},{"@type":"ListItem","position":2,"name":"Rooms &#038; Suites","item":"https:\/\/schlosshotel-fleesensee.com\/en\/rooms-suites\/"},{"@type":"ListItem","position":3,"name":"Rooms","item":"https:\/\/schlosshotel-fleesensee.com\/en\/rooms-suites\/rooms\/"},{"@type":"ListItem","position":4,"name":"Park Rooms"}]},{"@type":"WebSite","@id":"https:\/\/schlosshotel-fleesensee.com\/en\/#website","url":"https:\/\/schlosshotel-fleesensee.com\/en\/","name":"Schlosshotel Fleesensee","description":"Endlich Urlaub. Endlich Ich.","publisher":{"@id":"https:\/\/schlosshotel-fleesensee.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schlosshotel-fleesensee.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/schlosshotel-fleesensee.com\/en\/#organization","name":"Fleesensee Schlosshotel GmbH","url":"https:\/\/schlosshotel-fleesensee.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/schlosshotel-fleesensee.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/schlosshotel-fleesensee.com\/wp-content\/uploads\/2021\/12\/schloss_fleesensee_logo.svg","contentUrl":"https:\/\/schlosshotel-fleesensee.com\/wp-content\/uploads\/2021\/12\/schloss_fleesensee_logo.svg","width":77,"height":120,"caption":"Fleesensee Schlosshotel GmbH"},"image":{"@id":"https:\/\/schlosshotel-fleesensee.com\/en\/#\/schema\/logo\/image\/"}}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/schlosshotel-fleesensee.com\/en\/wp-json\/wp\/v2\/pages\/17210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schlosshotel-fleesensee.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/schlosshotel-fleesensee.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/schlosshotel-fleesensee.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/schlosshotel-fleesensee.com\/en\/wp-json\/wp\/v2\/comments?post=17210"}],"version-history":[{"count":5,"href":"https:\/\/schlosshotel-fleesensee.com\/en\/wp-json\/wp\/v2\/pages\/17210\/revisions"}],"predecessor-version":[{"id":18308,"href":"https:\/\/schlosshotel-fleesensee.com\/en\/wp-json\/wp\/v2\/pages\/17210\/revisions\/18308"}],"up":[{"embeddable":true,"href":"https:\/\/schlosshotel-fleesensee.com\/en\/wp-json\/wp\/v2\/pages\/17199"}],"wp:attachment":[{"href":"https:\/\/schlosshotel-fleesensee.com\/en\/wp-json\/wp\/v2\/media?parent=17210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}